{"id":14885,"date":"2020-05-10T23:11:32","date_gmt":"2020-05-10T21:11:32","guid":{"rendered":"https:\/\/shop.ilmannarino.it\/?post_type=product&#038;p=14885"},"modified":"2025-04-18T15:40:22","modified_gmt":"2025-04-18T13:40:22","slug":"olive-bella-di-cerignola","status":"publish","type":"product","link":"https:\/\/shop.ilmannarino.it\/en\/olive-bella-di-cerignola\/","title":{"rendered":"Bella di Cerignola olives"},"content":{"rendered":"<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<p>Oliva Bella of Cerignola<\/p>\n<p>Queen of the table and aperitifs<\/p>\n<p>560 g (drained weight 350 g)<\/p>\n<p>Green olives PDO 'la Bella di Cerignola' are an exquisite variety of table olives, well known for their volume and flesh consistency.<\/p>\n<p><em>For shipping information see <a href=\"https:\/\/shop.ilmannarino.it\/en\/spedizioni-consegne\/\">this page.<\/a><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<p>Queen of the table and of aperitifs.<\/p>\n<div>560 g.<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":25104,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[80],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-14885","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dispensa","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"bundle_layout":"","bundled_by":[],"bundled_items":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olive Bella di Cerignola del Mannarino a casa tua, con il pacco.<\/title>\n<meta name=\"description\" content=\"Olive Bella di Cerignola del Mannarino. Dalla dispensa del Mannarino a casa tua. Spedizione gratuita per ordini superiori a \u20ac35!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.ilmannarino.it\/en\/olive-bella-di-cerignola\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olive Bella di Cerignola del Mannarino a casa tua, con il pacco.\" \/>\n<meta property=\"og:description\" content=\"Olive Bella di Cerignola del Mannarino. Dalla dispensa del Mannarino a casa tua. Spedizione gratuita per ordini superiori a \u20ac35!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.ilmannarino.it\/en\/olive-bella-di-cerignola\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Mannarino Shop - Macelleria Online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilmannarino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T13:40:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2020\/12\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/\",\"url\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/\",\"name\":\"Olive Bella di Cerignola del Mannarino a casa tua, con il pacco.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.ilmannarino.it\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png\",\"datePublished\":\"2020-05-10T21:11:32+00:00\",\"dateModified\":\"2025-04-18T13:40:22+00:00\",\"description\":\"Olive Bella di Cerignola del Mannarino. Dalla dispensa del Mannarino a casa tua. Spedizione gratuita per ordini superiori a \u20ac35!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.ilmannarino.it\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png\",\"contentUrl\":\"https:\\\/\\\/shop.ilmannarino.it\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png\",\"width\":1024,\"height\":1024,\"caption\":\"olive bella di cerignola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/olive-bella-di-cerignola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shop.ilmannarino.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/shop.ilmannarino.it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Olive Bella di Cerignola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#website\",\"url\":\"https:\\\/\\\/shop.ilmannarino.it\\\/\",\"name\":\"Il Mannarino Shop - Macelleria Online\",\"description\":\"Scelto. Tagliato. Grigliato\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.ilmannarino.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#organization\",\"name\":\"Il Mannarino Shop Online\",\"url\":\"https:\\\/\\\/shop.ilmannarino.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.ilmannarino.it\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-il-mannarino-2022.svg\",\"contentUrl\":\"https:\\\/\\\/shop.ilmannarino.it\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-il-mannarino-2022.svg\",\"width\":207.412,\"height\":72.457,\"caption\":\"Il Mannarino Shop Online\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.ilmannarino.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilmannarino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ilmannarino\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mannarino's Bella di Cerignola olives at your doorstep.","description":"Mannarino's Bella di Cerignola olives. From Mannarino's pantry to your home. Free shipping on orders over \u20ac35!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.ilmannarino.it\/en\/olive-bella-di-cerignola\/","og_locale":"en_GB","og_type":"article","og_title":"Olive Bella di Cerignola del Mannarino a casa tua, con il pacco.","og_description":"Olive Bella di Cerignola del Mannarino. Dalla dispensa del Mannarino a casa tua. Spedizione gratuita per ordini superiori a \u20ac35!","og_url":"https:\/\/shop.ilmannarino.it\/en\/olive-bella-di-cerignola\/","og_site_name":"Il Mannarino Shop - Macelleria Online","article_publisher":"https:\/\/www.facebook.com\/ilmannarino\/","article_modified_time":"2025-04-18T13:40:22+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2020\/12\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/","url":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/","name":"Mannarino's Bella di Cerignola olives at your doorstep.","isPartOf":{"@id":"https:\/\/shop.ilmannarino.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/#primaryimage"},"image":{"@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2020\/12\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png","datePublished":"2020-05-10T21:11:32+00:00","dateModified":"2025-04-18T13:40:22+00:00","description":"Mannarino's Bella di Cerignola olives. From Mannarino's pantry to your home. Free shipping on orders over \u20ac35!","breadcrumb":{"@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/#primaryimage","url":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2020\/12\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png","contentUrl":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2020\/12\/pom-secchi-ok-1024x1024_0005_2020_12_01_Mannarino_0012.png","width":1024,"height":1024,"caption":"olive bella di cerignola"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.ilmannarino.it\/olive-bella-di-cerignola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.ilmannarino.it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/shop.ilmannarino.it\/shop\/"},{"@type":"ListItem","position":3,"name":"Olive Bella di Cerignola"}]},{"@type":"WebSite","@id":"https:\/\/shop.ilmannarino.it\/#website","url":"https:\/\/shop.ilmannarino.it\/","name":"The Mannarino Shop - Butcher Shop Online","description":"Chosen. Cut. Gridded","publisher":{"@id":"https:\/\/shop.ilmannarino.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.ilmannarino.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/shop.ilmannarino.it\/#organization","name":"The Mannarino Shop Online","url":"https:\/\/shop.ilmannarino.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/shop.ilmannarino.it\/#\/schema\/logo\/image\/","url":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2022\/02\/logo-il-mannarino-2022.svg","contentUrl":"https:\/\/shop.ilmannarino.it\/wp-content\/uploads\/2022\/02\/logo-il-mannarino-2022.svg","width":207.412,"height":72.457,"caption":"Il Mannarino Shop Online"},"image":{"@id":"https:\/\/shop.ilmannarino.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilmannarino\/","https:\/\/www.instagram.com\/ilmannarino\/"]}]}},"_links":{"self":[{"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/product\/14885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/media\/25104"}],"wp:attachment":[{"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/media?parent=14885"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/product_brand?post=14885"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/product_cat?post=14885"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/product_tag?post=14885"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/shop.ilmannarino.it\/en\/wp-json\/wp\/v2\/giftcard-category?post=14885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}